{"id":42743,"date":"2026-01-28T23:02:57","date_gmt":"2026-01-28T22:02:57","guid":{"rendered":"https:\/\/ccmprimaire.be\/wp\/?p=42743"},"modified":"2026-01-28T23:03:09","modified_gmt":"2026-01-28T22:03:09","slug":"cdn-jour-6-2","status":"publish","type":"post","link":"https:\/\/ccmprimaire.be\/wp\/cdn-jour-6-2\/","title":{"rendered":"CDN jour 6"},"content":{"rendered":"\n<p>Aujourd&rsquo;hui, il a neig\u00e9 sans arr\u00eat mais les enfants ont ski\u00e9 comme des pros. <\/p>\n\n\n\n<p>La fatigue et le froid \u00e9tant bien pr\u00e9sents, nous avons d\u00e9cid\u00e9 de passer le reste de la journ\u00e9e \u00e0 l&rsquo;h\u00f4tel. Gr\u00e2ce \u00e0 M. Daniel, les enfants ont pu jouer dans 27 ateliers m\u00ealant jeux en bois, jeux d&rsquo;adresse et art. <\/p>\n\n\n\n<p>Apr\u00e8s cela, ce fut le temps des grands pr\u00e9paratifs de d\u00e9part. Toutes les valises sont faites et c&rsquo;est presque pli\u00e9 partout \ud83d\ude09 .<\/p>\n\n\n\n<p>Apr\u00e8s un bon repas, le temps \u00e9tait venu de faire une merveilleuse marche aux flambeaux et d&rsquo;\u00e9couter une derni\u00e8re fois les bruits de la montagne. <\/p>\n\n\n\n<p>Cette journ\u00e9e s&rsquo;est cl\u00f4tur\u00e9e par un feu d&rsquo;artifice qui a \u00e9mu toute l&rsquo;assembl\u00e9e. <\/p>\n\n\n\n<p>Demain s&rsquo;annonce comme \u00e9tant une splendide journ\u00e9e, de quoi profiter une derni\u00e8re fois avant de rentrer. <\/p>\n\n\n\n<p>Gros bisous les parents \ud83d\ude42<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"950\" height=\"713\" data-attachment-id=\"42754\" data-permalink=\"https:\/\/ccmprimaire.be\/wp\/cdn-jour-6-2\/img_20260128_152722209_hdr_ae6807113946192055589-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_152722209_hdr_ae6807113946192055589-1.jpg?fit=2000%2C1500&amp;ssl=1\" data-orig-size=\"2000,1500\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;motorola edge 50 pro&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1769614042&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;5.895&quot;,&quot;iso&quot;:&quot;594&quot;,&quot;shutter_speed&quot;:&quot;0.02&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"img_20260128_152722209_hdr_ae6807113946192055589\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_152722209_hdr_ae6807113946192055589-1.jpg?fit=950%2C713&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_152722209_hdr_ae6807113946192055589-1.jpg?resize=950%2C713&#038;ssl=1\" alt=\"\" class=\"wp-image-42754\" srcset=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_152722209_hdr_ae6807113946192055589-1.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_152722209_hdr_ae6807113946192055589-1.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_152722209_hdr_ae6807113946192055589-1.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_152722209_hdr_ae6807113946192055589-1.jpg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_152722209_hdr_ae6807113946192055589-1.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_152722209_hdr_ae6807113946192055589-1.jpg?w=2000&amp;ssl=1 2000w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_152722209_hdr_ae6807113946192055589-1.jpg?w=1900&amp;ssl=1 1900w\" sizes=\"(max-width: 950px) 100vw, 950px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"950\" height=\"713\" data-attachment-id=\"42747\" data-permalink=\"https:\/\/ccmprimaire.be\/wp\/cdn-jour-6-2\/img_20260128_152729261_hdr_ae8751773999530536992\/\" data-orig-file=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_152729261_hdr_ae8751773999530536992.jpg?fit=2000%2C1500&amp;ssl=1\" data-orig-size=\"2000,1500\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;motorola edge 50 pro&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1769614049&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;5.895&quot;,&quot;iso&quot;:&quot;494&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"img_20260128_152729261_hdr_ae8751773999530536992\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_152729261_hdr_ae8751773999530536992.jpg?fit=950%2C713&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_152729261_hdr_ae8751773999530536992.jpg?resize=950%2C713&#038;ssl=1\" alt=\"\" class=\"wp-image-42747\" srcset=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_152729261_hdr_ae8751773999530536992.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_152729261_hdr_ae8751773999530536992.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_152729261_hdr_ae8751773999530536992.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_152729261_hdr_ae8751773999530536992.jpg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_152729261_hdr_ae8751773999530536992.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_152729261_hdr_ae8751773999530536992.jpg?w=2000&amp;ssl=1 2000w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_152729261_hdr_ae8751773999530536992.jpg?w=1900&amp;ssl=1 1900w\" sizes=\"(max-width: 950px) 100vw, 950px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"950\" height=\"713\" data-attachment-id=\"42745\" data-permalink=\"https:\/\/ccmprimaire.be\/wp\/cdn-jour-6-2\/img_20260128_152749808_hdr_ae3026781235607944710\/\" data-orig-file=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_152749808_hdr_ae3026781235607944710.jpg?fit=2000%2C1500&amp;ssl=1\" data-orig-size=\"2000,1500\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;motorola edge 50 pro&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1769614070&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;5.895&quot;,&quot;iso&quot;:&quot;328&quot;,&quot;shutter_speed&quot;:&quot;0.02&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"img_20260128_152749808_hdr_ae3026781235607944710\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_152749808_hdr_ae3026781235607944710.jpg?fit=950%2C713&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_152749808_hdr_ae3026781235607944710.jpg?resize=950%2C713&#038;ssl=1\" alt=\"\" class=\"wp-image-42745\" srcset=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_152749808_hdr_ae3026781235607944710.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_152749808_hdr_ae3026781235607944710.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_152749808_hdr_ae3026781235607944710.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_152749808_hdr_ae3026781235607944710.jpg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_152749808_hdr_ae3026781235607944710.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_152749808_hdr_ae3026781235607944710.jpg?w=2000&amp;ssl=1 2000w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_152749808_hdr_ae3026781235607944710.jpg?w=1900&amp;ssl=1 1900w\" sizes=\"(max-width: 950px) 100vw, 950px\" \/><\/figure>\n\n\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"950\" height=\"713\" data-attachment-id=\"42755\" data-permalink=\"https:\/\/ccmprimaire.be\/wp\/cdn-jour-6-2\/img_20260128_152815949_hdr_ae5120384451364548168\/\" data-orig-file=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_152815949_hdr_ae5120384451364548168.jpg?fit=2000%2C1500&amp;ssl=1\" data-orig-size=\"2000,1500\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;motorola edge 50 pro&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1769614096&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;5.895&quot;,&quot;iso&quot;:&quot;403&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"img_20260128_152815949_hdr_ae5120384451364548168\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_152815949_hdr_ae5120384451364548168.jpg?fit=950%2C713&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_152815949_hdr_ae5120384451364548168.jpg?resize=950%2C713&#038;ssl=1\" alt=\"\" class=\"wp-image-42755\" srcset=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_152815949_hdr_ae5120384451364548168.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_152815949_hdr_ae5120384451364548168.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_152815949_hdr_ae5120384451364548168.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_152815949_hdr_ae5120384451364548168.jpg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_152815949_hdr_ae5120384451364548168.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_152815949_hdr_ae5120384451364548168.jpg?w=2000&amp;ssl=1 2000w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_152815949_hdr_ae5120384451364548168.jpg?w=1900&amp;ssl=1 1900w\" sizes=\"(max-width: 950px) 100vw, 950px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"950\" height=\"713\" data-attachment-id=\"42756\" data-permalink=\"https:\/\/ccmprimaire.be\/wp\/cdn-jour-6-2\/img_20260128_152800922_hdr_ae4575131750376976628\/\" data-orig-file=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_152800922_hdr_ae4575131750376976628.jpg?fit=2000%2C1500&amp;ssl=1\" data-orig-size=\"2000,1500\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;motorola edge 50 pro&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1769614081&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;5.895&quot;,&quot;iso&quot;:&quot;541&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"img_20260128_152800922_hdr_ae4575131750376976628\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_152800922_hdr_ae4575131750376976628.jpg?fit=950%2C713&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_152800922_hdr_ae4575131750376976628.jpg?resize=950%2C713&#038;ssl=1\" alt=\"\" class=\"wp-image-42756\" srcset=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_152800922_hdr_ae4575131750376976628.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_152800922_hdr_ae4575131750376976628.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_152800922_hdr_ae4575131750376976628.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_152800922_hdr_ae4575131750376976628.jpg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_152800922_hdr_ae4575131750376976628.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_152800922_hdr_ae4575131750376976628.jpg?w=2000&amp;ssl=1 2000w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_152800922_hdr_ae4575131750376976628.jpg?w=1900&amp;ssl=1 1900w\" sizes=\"(max-width: 950px) 100vw, 950px\" \/><\/figure>\n\n\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-attachment-id=\"42749\" data-permalink=\"https:\/\/ccmprimaire.be\/wp\/cdn-jour-6-2\/img_20260128_192825803_hdr_ae4373726221122672944\/\" data-orig-file=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_192825803_hdr_ae4373726221122672944.jpg?fit=1500%2C2000&amp;ssl=1\" data-orig-size=\"1500,2000\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;motorola edge 50 pro&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1769628506&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;5.895&quot;,&quot;iso&quot;:&quot;750&quot;,&quot;shutter_speed&quot;:&quot;0.02&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"img_20260128_192825803_hdr_ae4373726221122672944\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_192825803_hdr_ae4373726221122672944.jpg?fit=768%2C1024&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_192825803_hdr_ae4373726221122672944.jpg?resize=768%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-42749\" srcset=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_192825803_hdr_ae4373726221122672944.jpg?resize=768%2C1024&amp;ssl=1 768w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_192825803_hdr_ae4373726221122672944.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_192825803_hdr_ae4373726221122672944.jpg?resize=113%2C150&amp;ssl=1 113w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_192825803_hdr_ae4373726221122672944.jpg?resize=1152%2C1536&amp;ssl=1 1152w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_192825803_hdr_ae4373726221122672944.jpg?w=1500&amp;ssl=1 1500w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"950\" height=\"713\" data-attachment-id=\"42750\" data-permalink=\"https:\/\/ccmprimaire.be\/wp\/cdn-jour-6-2\/img_20260128_193134955_hdr_ae5251289645684157029\/\" data-orig-file=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_193134955_hdr_ae5251289645684157029.jpg?fit=2000%2C1500&amp;ssl=1\" data-orig-size=\"2000,1500\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;motorola edge 50 pro&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1769628695&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;5.895&quot;,&quot;iso&quot;:&quot;688&quot;,&quot;shutter_speed&quot;:&quot;0.02&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"img_20260128_193134955_hdr_ae5251289645684157029\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_193134955_hdr_ae5251289645684157029.jpg?fit=950%2C713&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_193134955_hdr_ae5251289645684157029.jpg?resize=950%2C713&#038;ssl=1\" alt=\"\" class=\"wp-image-42750\" srcset=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_193134955_hdr_ae5251289645684157029.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_193134955_hdr_ae5251289645684157029.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_193134955_hdr_ae5251289645684157029.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_193134955_hdr_ae5251289645684157029.jpg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_193134955_hdr_ae5251289645684157029.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_193134955_hdr_ae5251289645684157029.jpg?w=2000&amp;ssl=1 2000w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img_20260128_193134955_hdr_ae5251289645684157029.jpg?w=1900&amp;ssl=1 1900w\" sizes=\"(max-width: 950px) 100vw, 950px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-attachment-id=\"42752\" data-permalink=\"https:\/\/ccmprimaire.be\/wp\/cdn-jour-6-2\/img-20260128-wa00153202041512657644338\/\" data-orig-file=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img-20260128-wa00153202041512657644338.jpg?fit=1200%2C1600&amp;ssl=1\" data-orig-size=\"1200,1600\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"img-20260128-wa00153202041512657644338\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img-20260128-wa00153202041512657644338.jpg?fit=768%2C1024&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img-20260128-wa00153202041512657644338.jpg?resize=768%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-42752\" srcset=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img-20260128-wa00153202041512657644338.jpg?resize=768%2C1024&amp;ssl=1 768w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img-20260128-wa00153202041512657644338.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img-20260128-wa00153202041512657644338.jpg?resize=113%2C150&amp;ssl=1 113w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img-20260128-wa00153202041512657644338.jpg?resize=1152%2C1536&amp;ssl=1 1152w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img-20260128-wa00153202041512657644338.jpg?w=1200&amp;ssl=1 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-attachment-id=\"42753\" data-permalink=\"https:\/\/ccmprimaire.be\/wp\/cdn-jour-6-2\/img-20260128-wa00168024820900474343456\/\" data-orig-file=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img-20260128-wa00168024820900474343456.jpg?fit=1500%2C2000&amp;ssl=1\" data-orig-size=\"1500,2000\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"img-20260128-wa00168024820900474343456\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img-20260128-wa00168024820900474343456.jpg?fit=768%2C1024&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img-20260128-wa00168024820900474343456.jpg?resize=768%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-42753\" srcset=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img-20260128-wa00168024820900474343456.jpg?resize=768%2C1024&amp;ssl=1 768w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img-20260128-wa00168024820900474343456.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img-20260128-wa00168024820900474343456.jpg?resize=113%2C150&amp;ssl=1 113w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img-20260128-wa00168024820900474343456.jpg?resize=1152%2C1536&amp;ssl=1 1152w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img-20260128-wa00168024820900474343456.jpg?w=1500&amp;ssl=1 1500w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"473\" height=\"1024\" data-attachment-id=\"42751\" data-permalink=\"https:\/\/ccmprimaire.be\/wp\/cdn-jour-6-2\/img-20260128-wa00181786131375932126948\/\" data-orig-file=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img-20260128-wa00181786131375932126948.jpg?fit=739%2C1600&amp;ssl=1\" data-orig-size=\"739,1600\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"img-20260128-wa00181786131375932126948\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img-20260128-wa00181786131375932126948.jpg?fit=473%2C1024&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img-20260128-wa00181786131375932126948.jpg?resize=473%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-42751\" srcset=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img-20260128-wa00181786131375932126948.jpg?resize=473%2C1024&amp;ssl=1 473w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img-20260128-wa00181786131375932126948.jpg?resize=139%2C300&amp;ssl=1 139w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img-20260128-wa00181786131375932126948.jpg?resize=69%2C150&amp;ssl=1 69w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img-20260128-wa00181786131375932126948.jpg?resize=709%2C1536&amp;ssl=1 709w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/01\/img-20260128-wa00181786131375932126948.jpg?w=739&amp;ssl=1 739w\" sizes=\"(max-width: 473px) 100vw, 473px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Aujourd&rsquo;hui, il a neig\u00e9 sans arr\u00eat mais les enfants ont ski\u00e9 comme des pros. La fatigue et le froid \u00e9tant bien pr\u00e9sents, nous avons d\u00e9cid\u00e9 de passer le reste de la journ\u00e9e \u00e0 l&rsquo;h\u00f4tel. Gr\u00e2ce \u00e0 M. Daniel, les enfants ont pu jouer dans 27 ateliers m\u00ealant jeux en bois,\u2026 <a class=\"continue-reading-link\" href=\"https:\/\/ccmprimaire.be\/wp\/cdn-jour-6-2\/\">Lire la suite<\/a><\/p>\n","protected":false},"author":305,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[9],"tags":[],"class_list":["post-42743","post","type-post","status-publish","format-standard","hentry","category-actualites-de-lecole"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p6UVqj-b7p","jetpack-related-posts":[{"id":9399,"url":"https:\/\/ccmprimaire.be\/wp\/classes-de-neige-nouvelles-de-ce-samedi\/","url_meta":{"origin":42743,"position":0},"title":"Classes de neige: nouvelles de ce samedi","author":"Mr Arnaud","date":"18 mars 2017","format":false,"excerpt":"Voil\u00e0 d\u00e9j\u00e0 la premi\u00e8re journ\u00e9e qui se termine.\u00a0Une belle journ\u00e9e bien remplie ! Au programme: Premier r\u00e9veil anim\u00e9 pour Ga\u00eblle et Florian qui f\u00eataient aujourd'hui leur anniversaire. Nous avons commenc\u00e9 la journ\u00e9e par le ski. Entre soleil et passages nuageux, les enfants ont v\u00e9cu leur premier cours de ski sous\u2026","rel":"","context":"Dans &quot;Actualit\u00e9s de l'\u00e9cole&quot;","block_context":{"text":"Actualit\u00e9s de l'\u00e9cole","link":"https:\/\/ccmprimaire.be\/wp\/category\/actualites-de-lecole\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2017\/03\/DSC_0024.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2017\/03\/DSC_0024.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2017\/03\/DSC_0024.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2017\/03\/DSC_0024.jpg?resize=700%2C400 2x"},"classes":[]},{"id":17119,"url":"https:\/\/ccmprimaire.be\/wp\/notre-premiere-journee-a-mambaye\/","url_meta":{"origin":42743,"position":1},"title":"Notre premi\u00e8re journ\u00e9e \u00e0 Mambaye","author":"Dominique Mathon","date":"8 octobre 2018","format":false,"excerpt":"Bonjour, Apr\u00e8s un voyage sans encombre, nous arrivons au Domaine de Mambaye sous un soleil radieux. Apr\u00e8s un bon spaghetti revigorant, les enfants d\u00e9couvrent leurs chambres, s'installent et profitent de chouettes jeux avec les moniteurs. Ils nous ont pr\u00e9par\u00e9 une superbe activit\u00e9 \"Cranium\". Apr\u00e8s cette journ\u00e9e bien remplie, nous nous\u2026","rel":"","context":"Dans &quot;Les 3A&quot;","block_context":{"text":"Les 3A","link":"https:\/\/ccmprimaire.be\/wp\/category\/actualites-de-lecole\/les-classes\/les-troisiemes\/les-3a\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":39174,"url":"https:\/\/ccmprimaire.be\/wp\/cdn-jour-3\/","url_meta":{"origin":42743,"position":2},"title":"CDN jour 3","author":"Benjamin vt","date":"18 mars 2024","format":false,"excerpt":"Aujourd'hui, le soleil avait laiss\u00e9 sa place \u00e0 la pluie. Mais rien ne peut arr\u00eater nos super \u00e9l\u00e8ves. Ils ont ski\u00e9 et ont brav\u00e9 les \u00e9l\u00e9ments. Vous pouvez \u00eatre fiers d'eux! Apr\u00e8s une bonne douche chaude et un d\u00eener r\u00e9parateur, nous avons pass\u00e9 l'apr\u00e8s-midi \u00e0 jouer aux jeux en bois,\u2026","rel":"","context":"Dans &quot;Actualit\u00e9s de l'\u00e9cole&quot;","block_context":{"text":"Actualit\u00e9s de l'\u00e9cole","link":"https:\/\/ccmprimaire.be\/wp\/category\/actualites-de-lecole\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2024\/03\/collage_2024-03-18_17_06_457958611297675481882-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2024\/03\/collage_2024-03-18_17_06_457958611297675481882-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2024\/03\/collage_2024-03-18_17_06_457958611297675481882-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2024\/03\/collage_2024-03-18_17_06_457958611297675481882-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2024\/03\/collage_2024-03-18_17_06_457958611297675481882-1.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2024\/03\/collage_2024-03-18_17_06_457958611297675481882-1.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":25551,"url":"https:\/\/ccmprimaire.be\/wp\/rester-actif-meme-a-la-maison\/","url_meta":{"origin":42743,"position":3},"title":"Rester actif, m\u00eame \u00e0 la maison!","author":"Mr Arnaud","date":"29 mars 2020","format":false,"excerpt":"\u00c0 l'\u00e9cole comme \u00e0 la maison, faire de l'activit\u00e9 physique quotidiennement est toujours de mise! Si vous ne savez pas trop par o\u00f9 commencer et d\u00e9sirez trouver des activit\u00e9s dynamiques pour vous faire bouger, vous \u00eates au bon endroit! Le yoga et la m\u00e9ditation Le yoga et la m\u00e9ditation peuvent\u2026","rel":"","context":"Dans &quot;Actualit\u00e9s de l'\u00e9cole&quot;","block_context":{"text":"Actualit\u00e9s de l'\u00e9cole","link":"https:\/\/ccmprimaire.be\/wp\/category\/actualites-de-lecole\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/toupieyoga.com\/images\/fillette-yoga.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":33301,"url":"https:\/\/ccmprimaire.be\/wp\/p6-journee-sportive\/","url_meta":{"origin":42743,"position":4},"title":"P6: Journ\u00e9e sportive","author":"Mme Gaelle","date":"26 juin 2022","format":false,"excerpt":"Apr\u00e8s un bel effort pour passer leurs CEB, les \u00e9l\u00e8ves de P6 ont pu se d\u00e9fouler lors d'une journ\u00e9e sportive organis\u00e9e par M Daniel. Merci \u00e0 lui! Au programme: jeux dans la piscine, initiation \u00e0 l'escalade (en hauteur et en travers\u00e9e), jeux gonflables et kinball. Une chouette journ\u00e9e en images.\u2026","rel":"","context":"Dans &quot;Actualit\u00e9s de l'\u00e9cole&quot;","block_context":{"text":"Actualit\u00e9s de l'\u00e9cole","link":"https:\/\/ccmprimaire.be\/wp\/category\/actualites-de-lecole\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2022\/06\/IMG_9039-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2022\/06\/IMG_9039-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2022\/06\/IMG_9039-2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2022\/06\/IMG_9039-2.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2022\/06\/IMG_9039-2.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2022\/06\/IMG_9039-2.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":15460,"url":"https:\/\/ccmprimaire.be\/wp\/nouvelles-de-ce-mercredi-21-mars\/","url_meta":{"origin":42743,"position":5},"title":"Nouvelles de ce mercredi 21 mars","author":"Mr Arnaud","date":"21 mars 2018","format":false,"excerpt":"Bonsoir \u00e0 tous, Le contexte de ces deux derniers jours\u00a0? Soleil, ciel bleu, neige parfaite et ambiance au top\u00a0! Au menu (en dehors des p\u00e2tes)\u00a0? Des cours de ski dans des conditions id\u00e9ales, la deuxi\u00e8me \u00e9tape de notre tournante \u00ab\u00a0chiens de tra\u00eeneaux, scierie et bou\u00e9es\u00a0\u00bb, une d\u00e9couverte du glacier Presena\u2026","rel":"","context":"Dans &quot;Actualit\u00e9s de l'\u00e9cole&quot;","block_context":{"text":"Actualit\u00e9s de l'\u00e9cole","link":"https:\/\/ccmprimaire.be\/wp\/category\/actualites-de-lecole\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2018\/03\/DSC_0407.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2018\/03\/DSC_0407.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2018\/03\/DSC_0407.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2018\/03\/DSC_0407.jpg?resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/ccmprimaire.be\/wp\/wp-json\/wp\/v2\/posts\/42743","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccmprimaire.be\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccmprimaire.be\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccmprimaire.be\/wp\/wp-json\/wp\/v2\/users\/305"}],"replies":[{"embeddable":true,"href":"https:\/\/ccmprimaire.be\/wp\/wp-json\/wp\/v2\/comments?post=42743"}],"version-history":[{"count":1,"href":"https:\/\/ccmprimaire.be\/wp\/wp-json\/wp\/v2\/posts\/42743\/revisions"}],"predecessor-version":[{"id":42757,"href":"https:\/\/ccmprimaire.be\/wp\/wp-json\/wp\/v2\/posts\/42743\/revisions\/42757"}],"wp:attachment":[{"href":"https:\/\/ccmprimaire.be\/wp\/wp-json\/wp\/v2\/media?parent=42743"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccmprimaire.be\/wp\/wp-json\/wp\/v2\/categories?post=42743"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccmprimaire.be\/wp\/wp-json\/wp\/v2\/tags?post=42743"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}