{"id":38018,"date":"2023-08-22T09:45:48","date_gmt":"2023-08-22T07:45:48","guid":{"rendered":"https:\/\/ccmprimaire.be\/wp\/?p=38018"},"modified":"2023-08-22T09:46:49","modified_gmt":"2023-08-22T07:46:49","slug":"inscription-aux-etudes-2023-2024","status":"publish","type":"post","link":"https:\/\/ccmprimaire.be\/wp\/inscription-aux-etudes-2023-2024\/","title":{"rendered":"Inscription aux \u00e9tudes 2023 &#8211; 2024"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"950\" height=\"361\" data-attachment-id=\"25913\" data-permalink=\"https:\/\/ccmprimaire.be\/wp\/?attachment_id=25913\" data-orig-file=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2020\/08\/aux-etudes.png?fit=1025%2C390&amp;ssl=1\" data-orig-size=\"1025,390\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"aux-etudes\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2020\/08\/aux-etudes.png?fit=950%2C361&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2020\/08\/aux-etudes.png?resize=950%2C361&#038;ssl=1\" alt=\"\" class=\"wp-image-25913\" srcset=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2020\/08\/aux-etudes.png?w=1025&amp;ssl=1 1025w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2020\/08\/aux-etudes.png?resize=300%2C114&amp;ssl=1 300w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2020\/08\/aux-etudes.png?resize=150%2C57&amp;ssl=1 150w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2020\/08\/aux-etudes.png?resize=250%2C95&amp;ssl=1 250w\" sizes=\"(max-width: 950px) 100vw, 950px\" \/><\/figure>\n\n\n<p>Chers parents,<\/p>\n<p>Cette ann\u00e9e encore nous vous proposons un service d\u2019\u00e9tude adapt\u00e9 \u00e0 nos enfants de l\u2019\u00e9cole primaire. Les \u00e9tudes sont dirig\u00e9es par une ASBL regroupant toutes les \u00e9tudes ayant lieu au coll\u00e8ge tant au niveau primaire qu\u2019au niveau secondaire.<\/p>\n<p>Les \u00e9tudes primaires commencent \u00e0 15 h 40 (de 15h30 \u00e015h40 les \u00e9l\u00e8ves inscrits seront dans la grande cour sous la garde des surveillants habituels, tout \u00e9l\u00e8ve qui quitterait la cour durant ce laps de temps enfreindrait le r\u00e8glement de l\u2019\u00e9cole et ne serait plus sous la responsabilit\u00e9 de celle-ci ni sous celle de l\u2019ASBL) jusque 16h40 les lundis, mardis et jeudis dans un local classe et sous la responsabilit\u00e9 d\u2019un membre du personnel de l\u2019\u00e9cole primaire.<\/p>\n<p>Deux formules vous sont propos\u00e9es\u00a0:<\/p>\n<table>\n<tbody>\n<tr>\n<td>\n<p>0 L\u2019\u00e9tude surveill\u00e9e<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>0 L\u2019\u00e9tude dirig\u00e9e (groupe restreint \u00e0 partir de la 3\u00e8me primaire)<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Le paiement de ces \u00e9tudes se fera moyennant l\u2019achat d\u2019une \u00ab\u00a0carte \u00e9tude\u00a0\u00bb\u00a0: pour les \u00e9tudes surveill\u00e9es\u00a0: 55 Euros pour 20 s\u00e9ances, pour les \u00e9tudes dirig\u00e9es 60 Euros pour 10 s\u00e9ances. Ces cartes sont en vente aupr\u00e8s de Madame Dominique en 3A.<\/p>\n<p>L\u2019enfant ne disposant pas de carte valide ne sera pas accept\u00e9. En cas d\u2019absence \u00e0 une s\u00e9ance, l\u2019enfant devra pr\u00e9senter un mot \u00e9crit de ses parents responsables, si cette condition n\u2019est pas remplie la s\u00e9ance sera comptabilis\u00e9e sur la carte.<\/p>\n<p>Vous pouvez venir chercher votre enfant au moment de votre choix. Tout enfant quittant seul l\u2019\u00e9tude avant 16h40 ne pourra le faire que sur pr\u00e9sentation d\u2019un mot \u00e9crit des parents. Tous les enfants encore pr\u00e9sents \u00e0 16h40 seront conduits \u00e0 la garderie de l\u2019\u00e9cole primaire o\u00f9 ils devront s\u2019inscrire.<\/p>\n<p>Les \u00e9tudes d\u00e9buteront le lundi 4 septembre, veuillez cocher la case pour nous signaler que votre enfant sera pr\u00e9sent d\u00e8s ce premier jour. Au moment de la sonnerie de 15h40 les professeurs responsables descendront dans la cour et feront l\u2019appel des \u00e9l\u00e8ves inscrits dans leur \u00e9tude avant de les amener dans le local o\u00f9 aura lieu celle-ci. Pour tout renseignement (lieu, nom du professeur responsable\u2026) veuillez-vous adresser \u00e0 Madame Dominique en 3A ou par mail\u00a0: dominique.lauwers@ccm.be.<\/p>\n<p>Un enfant inscrit dans une \u00e9tude est tenu de se pr\u00e9senter aux jours dits. En cas d\u2019absence non signal\u00e9e, le matin au plus tard, la s\u00e9ance d\u2019\u00e9tude sera comptabilis\u00e9e.<\/p>\n<p>Inscription 2023-24<\/p>\n<p>Document \u00e0 imprimer et faire parvenir avant en 4A (en version papier SVP). Ecrire en imprim\u00e9 SVP.<\/p>\n<p>Mme, Mr \u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026. Parent responsable de<\/p>\n<p>Nom, pr\u00e9nom de l\u2019enfant \u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026.<\/p>\n<p>Classe de \u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026..<\/p>\n<p>Num\u00e9ro de t\u00e9l\u00e9phone (en cas d\u2019urgence durant l\u2019heure d\u2019\u00e9tude)\u00a0: \u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026<\/p>\n<p>Adresse mail\u00a0: \u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026..<\/p>\n<p>A bien pris connaissance des conditions et d\u00e9sire inscrire son enfant dans (cocher)<\/p>\n<table>\n<tbody>\n<tr>\n<td>\n<p><strong>0 une \u00e9tude surveill\u00e9e<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p><strong>0 une \u00e9tude dirig\u00e9e<\/strong><\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Jours de fr\u00e9quentation (entourer)<\/p>\n<table>\n<tbody>\n<tr>\n<td>\n<p><strong>lundi<\/strong><\/p>\n<\/td>\n<td>\n<p><strong>mardi<\/strong><\/p>\n<\/td>\n<td>\n<p><strong>Jeudi<\/strong><\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><strong>Mon enfant commencera l\u2019\u00e9tude O le 4 septembre<\/strong><\/p>\n<p><strong> O le \u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026..<\/strong><\/p>\n<p><strong>Le premier achat de la \u00ab\u00a0carte \u00e9tude\u00a0\u00bb fait office d\u2019inscription d\u00e9finitive. Veuillez joindre la somme correspondante \u00e0 votre choix (55 ou 60 Euros) au document r\u00e9ponse d\u00fbment compl\u00e9t\u00e9 et faire parvenir le tout sous enveloppe avec le nom et la classe de l\u2019enfant en 3A. Cela est obligatoire m\u00eame s\u2019il vous a \u00e9t\u00e9 signal\u00e9 que votre enfant est d\u00e9tenteur d\u2019une carte encore valide, vous devez alors faire parvenir la fiche d\u2019inscription seule. <\/strong><\/p>\n<p>Les \u00e9tudes ne b\u00e9n\u00e9ficient pas de la d\u00e9duction fiscale.<\/p>\n<p>0 Mon enfant d\u00e9butera l\u2019\u00e9tude le \u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026.<\/p>\n<p>Signature\u00a0:<\/p>\n<p>Vous pouvez nous joindre via l\u2019adresse mail suivante\u00a0: dominique.lauwers@ccm.be<\/p>\n<p>Un document incomplet ou sans paiement ne sera pas pris en compte.<\/p>\n<p>T\u00e9l\u00e9charger le document: <a  data-e-Disable-Page-Transition=\"true\" class=\"download-link\" title=\"\" href=\"https:\/\/ccmprimaire.be\/wp\/download\/38012\/?tmstv=1778713853\" rel=\"nofollow\" id=\"download-link-38012\" data-redirect=\"false\" >\n\tEtude 2023 - 2024<\/a>\n<\/p>","protected":false},"excerpt":{"rendered":"<p>Chers parents, Cette ann\u00e9e encore nous vous proposons un service d\u2019\u00e9tude adapt\u00e9 \u00e0 nos enfants de l\u2019\u00e9cole primaire. Les \u00e9tudes sont dirig\u00e9es par une ASBL regroupant toutes les \u00e9tudes ayant lieu au coll\u00e8ge tant au niveau primaire qu\u2019au niveau secondaire. Les \u00e9tudes primaires commencent \u00e0 15 h 40 (de 15h30\u2026 <a class=\"continue-reading-link\" href=\"https:\/\/ccmprimaire.be\/wp\/inscription-aux-etudes-2023-2024\/\">Lire la suite<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[9],"tags":[],"class_list":["post-38018","post","type-post","status-publish","format-standard","hentry","category-actualites-de-lecole"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p6UVqj-9Tc","jetpack-related-posts":[{"id":33794,"url":"https:\/\/ccmprimaire.be\/wp\/inscriptions-aux-etudes-2022\/","url_meta":{"origin":38018,"position":0},"title":"Inscriptions aux \u00e9tudes 2022","author":"Mr Arnaud","date":"25 ao\u00fbt 2022","format":false,"excerpt":"Chers parents, Cette ann\u00e9e encore nous vous proposons un service d\u2019\u00e9tude adapt\u00e9 \u00e0 nos enfants de l\u2019\u00e9cole primaire. Les \u00e9tudes sont dirig\u00e9es par une ASBL regroupant toutes les \u00e9tudes ayant lieu au coll\u00e8ge tant au niveau primaire qu\u2019au niveau secondaire. Les \u00e9tudes primaires commencent \u00e0 15 h 40 (de 15h30\u2026","rel":"","context":"Dans &quot;Actualit\u00e9s de l'\u00e9cole&quot;","block_context":{"text":"Actualit\u00e9s de l'\u00e9cole","link":"https:\/\/ccmprimaire.be\/wp\/category\/actualites-de-lecole\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2020\/08\/aux-etudes.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2020\/08\/aux-etudes.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2020\/08\/aux-etudes.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2020\/08\/aux-etudes.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":25902,"url":"https:\/\/ccmprimaire.be\/wp\/une-rentree-scolaire-en-couleurs\/","url_meta":{"origin":38018,"position":1},"title":"UNE RENTREE SCOLAIRE EN COULEURS","author":"Mr Arnaud","date":"25 ao\u00fbt 2020","format":false,"excerpt":"\u00a0 Chers Parents, C\u2019est avec plaisir que je vous envoie ce courrier de rentr\u00e9e. En effet, il est temps de se pr\u00e9parer pour ce moment si particulier et important dans la vie de tous les \u00e9coliers. Apr\u00e8s une ann\u00e9e scolaire 2019\/2020 compliqu\u00e9e et chaotique, la rentr\u00e9e s\u2019annonce plus classique selon\u2026","rel":"","context":"Dans &quot;Actualit\u00e9s de l'\u00e9cole&quot;","block_context":{"text":"Actualit\u00e9s de l'\u00e9cole","link":"https:\/\/ccmprimaire.be\/wp\/category\/actualites-de-lecole\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2020\/08\/date-300x300.png?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":33805,"url":"https:\/\/ccmprimaire.be\/wp\/rentree-des-classes\/","url_meta":{"origin":38018,"position":2},"title":"Rentr\u00e9e des classes","author":"Mr Arnaud","date":"27 ao\u00fbt 2022","format":false,"excerpt":"Quelques infos concernant la rentr\u00e9e des classes: LUNDI 29 AOUT.La garderie d\u00e9butera d\u00e8s 07h00 au b\u00e2timent C ( salle de gymnastique) et se terminera \u00e0 18h au b\u00e2timent K (Kwest\/r\u00e9fectoire). Aucune d\u00e9marche pr\u00e9alable n\u2019est \u00e0 faire pour ce premier jour.Les enfants sont attendus au plus tard \u00e0 8h30 dans leurs\u2026","rel":"","context":"Dans &quot;Actualit\u00e9s de l'\u00e9cole&quot;","block_context":{"text":"Actualit\u00e9s de l'\u00e9cole","link":"https:\/\/ccmprimaire.be\/wp\/category\/actualites-de-lecole\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":26709,"url":"https:\/\/ccmprimaire.be\/wp\/braine-lalleud-le-directeur-de-lecole-primaire-du-college-cardinal-mercier-denonce-le-sous-financement-chronique-de-lenseignement-fondamental\/","url_meta":{"origin":38018,"position":3},"title":"Braine-l&rsquo;Alleud: le directeur de l&rsquo;\u00e9cole primaire du Coll\u00e8ge Cardinal Mercier d\u00e9nonce le sous-financement chronique de l&rsquo;enseignement fondamental","author":"Mr Arnaud","date":"21 octobre 2020","format":false,"excerpt":"Photo du 13 avril 2009 avec la statue inaugur\u00e9e en 1935, l'h\u00f4tellerie ou b\u00e2timent B (1928) et \u00e0 l'arri\u00e8re-plan, la salle de gymnastique (1981) de l'Ecole primaire. Photo : Jean-Fran\u00e7ois Piraux. Un article de M Hendrickx sur le site de la RTBF Bruno Hendrickx est le directeur de l\u2019\u00e9cole primaire\u2026","rel":"","context":"Dans &quot;Actualit\u00e9s de l'\u00e9cole&quot;","block_context":{"text":"Actualit\u00e9s de l'\u00e9cole","link":"https:\/\/ccmprimaire.be\/wp\/category\/actualites-de-lecole\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2015\/10\/090413.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2015\/10\/090413.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2015\/10\/090413.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2015\/10\/090413.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":11916,"url":"https:\/\/ccmprimaire.be\/wp\/bonne-rentree\/","url_meta":{"origin":38018,"position":4},"title":"Bonne rentr\u00e9e","author":"Mr Arnaud","date":"30 ao\u00fbt 2017","format":false,"excerpt":"Chers Parents, C\u2019est avec un grand plaisir que je vous annonce que le Coll\u00e8ge se pr\u00e9pare depuis d\u00e9j\u00e0 plusieurs jours \u00e0 accueillir vos enfants pour une nouvelle ann\u00e9e d\u2019apprentissages, de d\u00e9couvertes et d\u2019aventures. Nous serons donc pr\u00eats ce vendredi premier septembre. Bien entendu, certaines informations pratiques et utiles doivent vous\u2026","rel":"","context":"Dans &quot;Actualit\u00e9s de l'\u00e9cole&quot;","block_context":{"text":"Actualit\u00e9s de l'\u00e9cole","link":"https:\/\/ccmprimaire.be\/wp\/category\/actualites-de-lecole\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":30130,"url":"https:\/\/ccmprimaire.be\/wp\/rentree-des-classes-primaire\/","url_meta":{"origin":38018,"position":5},"title":"Rentr\u00e9e des classes \u00ab\u00a0primaire\u00a0\u00bb","author":"Mr Arnaud","date":"31 ao\u00fbt 2021","format":false,"excerpt":"Ce mercredi 1er septembre aura lieu la rentr\u00e9e des primaires.* La garderie d\u00e9butera \u00e0 07h00 au b\u00e2timent C (salle de gymnastique) et se terminera \u00e0 18h00 au b\u00e2timentK (au grand r\u00e9fectoire). A partir de 8h00, la garderie des maternelles sera d\u00e9localis\u00e9e dans une classematernelle (b\u00e2timent D)* Afin de permettre aux\u2026","rel":"","context":"Dans &quot;Actualit\u00e9s de l'\u00e9cole&quot;","block_context":{"text":"Actualit\u00e9s de l'\u00e9cole","link":"https:\/\/ccmprimaire.be\/wp\/category\/actualites-de-lecole\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2021\/08\/ccm.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2021\/08\/ccm.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2021\/08\/ccm.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/ccmprimaire.be\/wp\/wp-json\/wp\/v2\/posts\/38018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccmprimaire.be\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccmprimaire.be\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccmprimaire.be\/wp\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ccmprimaire.be\/wp\/wp-json\/wp\/v2\/comments?post=38018"}],"version-history":[{"count":3,"href":"https:\/\/ccmprimaire.be\/wp\/wp-json\/wp\/v2\/posts\/38018\/revisions"}],"predecessor-version":[{"id":38021,"href":"https:\/\/ccmprimaire.be\/wp\/wp-json\/wp\/v2\/posts\/38018\/revisions\/38021"}],"wp:attachment":[{"href":"https:\/\/ccmprimaire.be\/wp\/wp-json\/wp\/v2\/media?parent=38018"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccmprimaire.be\/wp\/wp-json\/wp\/v2\/categories?post=38018"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccmprimaire.be\/wp\/wp-json\/wp\/v2\/tags?post=38018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}