{"id":34532,"date":"2022-10-14T13:26:14","date_gmt":"2022-10-14T11:26:14","guid":{"rendered":"https:\/\/ccmprimaire.be\/wp\/?p=34532"},"modified":"2022-10-14T14:16:31","modified_gmt":"2022-10-14T12:16:31","slug":"6b-notre-oeuvre-planisphere","status":"publish","type":"post","link":"https:\/\/ccmprimaire.be\/wp\/6b-notre-oeuvre-planisphere\/","title":{"rendered":"6B: Notre \u0153uvre \u00ab\u00a0planisph\u00e8re\u00a0\u00bb"},"content":{"rendered":"\n<p>Apr\u00e8s avoir travaill\u00e9 sur les diverses repr\u00e9sentations de la Terre en g\u00e9ographie, voici notre \u0153uvre collaborative en art.<br><br><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"872\" height=\"646\" data-attachment-id=\"34534\" data-permalink=\"https:\/\/ccmprimaire.be\/wp\/6b-notre-oeuvre-planisphere\/image-3\/\" data-orig-file=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2022\/10\/image.png?fit=872%2C646&amp;ssl=1\" data-orig-size=\"872,646\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"image\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2022\/10\/image.png?fit=872%2C646&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2022\/10\/image.png?resize=872%2C646&#038;ssl=1\" alt=\"\" class=\"wp-image-34534\" srcset=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2022\/10\/image.png?w=872&amp;ssl=1 872w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2022\/10\/image.png?resize=300%2C222&amp;ssl=1 300w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2022\/10\/image.png?resize=150%2C111&amp;ssl=1 150w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2022\/10\/image.png?resize=202%2C150&amp;ssl=1 202w\" sizes=\"(max-width: 872px) 100vw, 872px\" \/><\/figure>\n\n\n","protected":false},"excerpt":{"rendered":"<p> <a class=\"continue-reading-link\" href=\"https:\/\/ccmprimaire.be\/wp\/6b-notre-oeuvre-planisphere\/\">Lire la suite<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[9,11],"tags":[],"class_list":["post-34532","post","type-post","status-publish","format-standard","hentry","category-actualites-de-lecole","category-les-6b"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p6UVqj-8YY","jetpack-related-posts":[{"id":26334,"url":"https:\/\/ccmprimaire.be\/wp\/6b-nos-oeuvres\/","url_meta":{"origin":34532,"position":0},"title":"6B: nos \u0153uvres","author":"Mr Arnaud","date":"13 octobre 2020","format":false,"excerpt":"Nos \u0153uvres du moment.","rel":"","context":"Dans &quot;Actualit\u00e9s de l'\u00e9cole&quot;","block_context":{"text":"Actualit\u00e9s de l'\u00e9cole","link":"https:\/\/ccmprimaire.be\/wp\/category\/actualites-de-lecole\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2020\/10\/arbres-21-rotated.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2020\/10\/arbres-21-rotated.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2020\/10\/arbres-21-rotated.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2020\/10\/arbres-21-rotated.jpg?resize=700%2C400 2x, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2020\/10\/arbres-21-rotated.jpg?resize=1050%2C600 3x, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2020\/10\/arbres-21-rotated.jpg?resize=1400%2C800 4x"},"classes":[]},{"id":10369,"url":"https:\/\/ccmprimaire.be\/wp\/loeuvre-du-jour-en-6b-marc-chagall\/","url_meta":{"origin":34532,"position":1},"title":"L\u2019oeuvre du jour en 6B \u2013 Marc Chagall","author":"Mr Arnaud","date":"26 mai 2017","format":false,"excerpt":"Suite de nos d\u00e9couvertes d\u2019oeuvre\u2026 Cette semaine, nous avons d\u00e9couvert\u00a0des oeuvres de Marc Chagall L\u2019oeuvre pr\u00e9f\u00e9r\u00e9e de la classe est\u00a0le tableau \"La Noce\".","rel":"","context":"Dans &quot;Actualit\u00e9s de l'\u00e9cole&quot;","block_context":{"text":"Actualit\u00e9s de l'\u00e9cole","link":"https:\/\/ccmprimaire.be\/wp\/category\/actualites-de-lecole\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2017\/05\/c.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":10474,"url":"https:\/\/ccmprimaire.be\/wp\/loeuvre-du-jour-en-6b-jean-de-la-fontaine\/","url_meta":{"origin":34532,"position":2},"title":"L\u2019oeuvre du jour en 6B \u2013 Jean de la Fontaine","author":"Mr Arnaud","date":"6 juin 2017","format":false,"excerpt":"Suite de nos d\u00e9couvertes d\u2019oeuvres\u2026 Cette semaine, nous avons d\u00e9couvert\u00a0des \u0153uvres de Jean de la Fontaine L\u2019oeuvre pr\u00e9f\u00e9r\u00e9e de la classe est\u00a0la fable \"Le li\u00e8vre et la tortue\"","rel":"","context":"Dans &quot;Actualit\u00e9s de l'\u00e9cole&quot;","block_context":{"text":"Actualit\u00e9s de l'\u00e9cole","link":"https:\/\/ccmprimaire.be\/wp\/category\/actualites-de-lecole\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2017\/06\/le-li%C3%A8vre.jpg?fit=631%2C367&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2017\/06\/le-li%C3%A8vre.jpg?fit=631%2C367&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2017\/06\/le-li%C3%A8vre.jpg?fit=631%2C367&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":16843,"url":"https:\/\/ccmprimaire.be\/wp\/6b-oeuvres-artistiques-du-moment\/","url_meta":{"origin":34532,"position":3},"title":"6B: oeuvres artistiques du moment","author":"Mr Arnaud","date":"1 octobre 2018","format":false,"excerpt":"Voici nos derni\u00e8res r\u00e9alisations artistiques (les couleurs donnent mieux \"en vrai\")","rel":"","context":"Dans &quot;Actualit\u00e9s de l'\u00e9cole&quot;","block_context":{"text":"Actualit\u00e9s de l'\u00e9cole","link":"https:\/\/ccmprimaire.be\/wp\/category\/actualites-de-lecole\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2018\/10\/SRVUNIFLOW_PRCANONE01_0010_014.jpg?fit=848%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2018\/10\/SRVUNIFLOW_PRCANONE01_0010_014.jpg?fit=848%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2018\/10\/SRVUNIFLOW_PRCANONE01_0010_014.jpg?fit=848%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2018\/10\/SRVUNIFLOW_PRCANONE01_0010_014.jpg?fit=848%2C1200&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":26271,"url":"https:\/\/ccmprimaire.be\/wp\/6b-notre-oeuvre-prenom\/","url_meta":{"origin":34532,"position":4},"title":"6B &#8211; Notre \u0153uvre \u00ab\u00a0pr\u00e9nom\u00a0\u00bb","author":"Mr Arnaud","date":"7 octobre 2020","format":false,"excerpt":"Voici notre \u0153uvre pr\u00e9nom.Consignes: \u00c9crire son pr\u00e9nom en entier, diviser la feuille en 4 zones.\u00a0 Chaque zone sera colori\u00e9e avec 2 - 3 couleurs diff\u00e9rentes.Le reste sera combl\u00e9 avec du noir. Exemple:","rel":"","context":"Dans &quot;Actualit\u00e9s de l'\u00e9cole&quot;","block_context":{"text":"Actualit\u00e9s de l'\u00e9cole","link":"https:\/\/ccmprimaire.be\/wp\/category\/actualites-de-lecole\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2020\/10\/qUZ3xGjCX_fbE19jGv7a2xljGZs.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2020\/10\/qUZ3xGjCX_fbE19jGv7a2xljGZs.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2020\/10\/qUZ3xGjCX_fbE19jGv7a2xljGZs.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2020\/10\/qUZ3xGjCX_fbE19jGv7a2xljGZs.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2020\/10\/qUZ3xGjCX_fbE19jGv7a2xljGZs.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":1454,"url":"https:\/\/ccmprimaire.be\/wp\/6b-un-jour-une-oeuvre\/","url_meta":{"origin":34532,"position":5},"title":"6B: un jour, une oeuvre","author":"Mr Arnaud","date":"10 novembre 2015","format":false,"excerpt":"En 6B, nous d\u00e9couvrons une oeuvre tous les jours. Cela va de la peinture, \u00e0 la musique en passant par la Grotte de Lascaux,... Nous faisons cela du lundi au jeudi et nous faisons une synth\u00e8se le vendredi. Ce lundi, nous avons d\u00e9couvert Duke Ellington et son morceau \"Caravan\" Ce\u2026","rel":"","context":"Dans &quot;Actualit\u00e9s de l'\u00e9cole&quot;","block_context":{"text":"Actualit\u00e9s de l'\u00e9cole","link":"https:\/\/ccmprimaire.be\/wp\/category\/actualites-de-lecole\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/ccmprimaire.be\/wp\/wp-json\/wp\/v2\/posts\/34532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccmprimaire.be\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccmprimaire.be\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccmprimaire.be\/wp\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ccmprimaire.be\/wp\/wp-json\/wp\/v2\/comments?post=34532"}],"version-history":[{"count":2,"href":"https:\/\/ccmprimaire.be\/wp\/wp-json\/wp\/v2\/posts\/34532\/revisions"}],"predecessor-version":[{"id":34536,"href":"https:\/\/ccmprimaire.be\/wp\/wp-json\/wp\/v2\/posts\/34532\/revisions\/34536"}],"wp:attachment":[{"href":"https:\/\/ccmprimaire.be\/wp\/wp-json\/wp\/v2\/media?parent=34532"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccmprimaire.be\/wp\/wp-json\/wp\/v2\/categories?post=34532"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccmprimaire.be\/wp\/wp-json\/wp\/v2\/tags?post=34532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}