{"id":29360,"date":"2021-04-12T17:03:22","date_gmt":"2021-04-12T15:03:22","guid":{"rendered":"http:\/\/ccmprimaire.be\/wp\/?page_id=29360"},"modified":"2026-01-14T11:31:05","modified_gmt":"2026-01-14T10:31:05","slug":"accueil","status":"publish","type":"page","link":"https:\/\/ccmprimaire.be\/wp\/","title":{"rendered":"Accueil"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"29360\" class=\"elementor elementor-29360\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7a3f424 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7a3f424\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-420326e\" data-id=\"420326e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-becb414 elementor-widget elementor-widget-html\" data-id=\"becb414\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div id=\"serious-slider-97-rnd8298\" class=\"cryout-serious-slider seriousslider serious-slider-97-rnd8298 serious-slider-97 seriousslider-overlay1 seriousslider-light2 seriousslider-shadow-level1 seriousslider-responsive-maintain seriousslider-hidetitles-0 seriousslider-slide seriousslider-sizing0 seriousslider-aligncenter seriousslider-caption-animation-slide seriousslider-textstyle-textshadow\" data-ride=\"seriousslider\">\n\t\t\t<div class=\"seriousslider-inner\" role=\"listbox\">\n\n\t\t\t\n\t\t\t<div class=\"item slide-1 active\" role=\"option\">\n\t\t\t\t\t\t\t\t<a  >\n\t\t\t\t\t<img decoding=\"async\" class=\"item-image\" src=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2026\/04\/Bon-conge-de-printemps.png?fit=2050%2C780&#038;ssl=1\" alt=\"\" >\n\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"seriousslider-hloader\"><\/div>\n\t\t\t\t<figure class=\"seriousslider-cloader\">\n\t\t\t\t\t<svg width=\"200\" height=\"200\">\n\t\t\t\t\t\t<circle cx=\"95\" cy=\"95\" r=\"20\" transform=\"rotate(-90, 95, 95)\"\/>\n\t\t\t\t\t<\/svg>\n\t\t\t  <\/figure>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\n\t\t\t<div class=\"seriousslider-indicators\">\n\t\t\t\t<ol class=\"seriousslider-indicators-inside\">\n\t\t\t\t\t\t\t\t\t\t<li data-target=\"#serious-slider-97\" data-slide-to=\"0\" class=\"active\"><\/li>\n\t\t\t\t\t\t\t\t\t<\/ol>\n\t\t\t<\/div>\n\n\t\t\t<button class=\"left seriousslider-control\" data-target=\"#serious-slider-97-rnd8298\" role=\"button\" data-slide=\"prev\">\n\t\t\t  <span class=\"sicon-prev control-arrow\" aria-hidden=\"true\"><\/span>\n\t\t\t  <span class=\"sr-only\">Previous Slide<\/span>\n\t\t\t<\/button>\n\t\t\t<button class=\"right seriousslider-control\" data-target=\"#serious-slider-97-rnd8298\" role=\"button\" data-slide=\"next\">\n\t\t\t  <span class=\"sicon-next control-arrow\" aria-hidden=\"true\"><\/span>\n\t\t\t  <span class=\"sr-only\">Next Slide<\/span>\n\t\t\t<\/button>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9134d6c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9134d6c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c87bf2a\" data-id=\"c87bf2a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8dd8420 elementor-widget elementor-widget-image\" data-id=\"8dd8420\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" data-attachment-id=\"42167\" data-permalink=\"https:\/\/ccmprimaire.be\/wp\/accueil\/ccm-7\/\" data-orig-file=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2025\/10\/ccm.png?fit=1024%2C576&amp;ssl=1\" data-orig-size=\"1024,576\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"ccm\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2025\/10\/ccm.png?fit=950%2C534&amp;ssl=1\" width=\"1024\" height=\"576\" src=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2025\/10\/ccm.png?fit=1024%2C576&amp;ssl=1\" class=\"attachment-1536x1536 size-1536x1536 wp-image-42167\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2025\/10\/ccm.png?w=1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2025\/10\/ccm.png?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2025\/10\/ccm.png?resize=150%2C84&amp;ssl=1 150w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2025\/10\/ccm.png?resize=250%2C141&amp;ssl=1 250w\" sizes=\"(max-width: 950px) 100vw, 950px\" data-attachment-id=\"42167\" data-permalink=\"https:\/\/ccmprimaire.be\/wp\/accueil\/ccm-7\/\" data-orig-file=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2025\/10\/ccm.png?fit=1024%2C576&amp;ssl=1\" data-orig-size=\"1024,576\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"ccm\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2025\/10\/ccm.png?fit=950%2C534&amp;ssl=1\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c19e791 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c19e791\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-efa0799\" data-id=\"efa0799\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-688c49c elementor-widget elementor-widget-image\" data-id=\"688c49c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" data-attachment-id=\"42173\" data-permalink=\"https:\/\/ccmprimaire.be\/wp\/accueil\/news-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2025\/10\/news.png?fit=456%2C436&amp;ssl=1\" data-orig-size=\"456,436\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"news\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2025\/10\/news.png?fit=456%2C436&amp;ssl=1\" width=\"456\" height=\"436\" src=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2025\/10\/news.png?fit=456%2C436&amp;ssl=1\" class=\"attachment-large size-large wp-image-42173\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2025\/10\/news.png?w=456&amp;ssl=1 456w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2025\/10\/news.png?resize=300%2C287&amp;ssl=1 300w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2025\/10\/news.png?resize=150%2C143&amp;ssl=1 150w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2025\/10\/news.png?resize=157%2C150&amp;ssl=1 157w\" sizes=\"(max-width: 456px) 100vw, 456px\" data-attachment-id=\"42173\" data-permalink=\"https:\/\/ccmprimaire.be\/wp\/accueil\/news-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2025\/10\/news.png?fit=456%2C436&amp;ssl=1\" data-orig-size=\"456,436\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"news\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2025\/10\/news.png?fit=456%2C436&amp;ssl=1\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d113e74 elementor-widget elementor-widget-text-editor\" data-id=\"d113e74\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Toute l&rsquo;actualit\u00e9\u00a0de l&rsquo;\u00e9cole\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c6d8e77 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"c6d8e77\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/ccmprimaire.be\/wp\/category\/actualites-de-lecole\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Plus d'infos<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-0978924\" data-id=\"0978924\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-629e86b elementor-widget elementor-widget-image\" data-id=\"629e86b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" data-attachment-id=\"42171\" data-permalink=\"https:\/\/ccmprimaire.be\/wp\/accueil\/calendrier-3\/\" data-orig-file=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2025\/10\/calendrier.png?fit=602%2C437&amp;ssl=1\" data-orig-size=\"602,437\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"calendrier\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2025\/10\/calendrier.png?fit=602%2C437&amp;ssl=1\" width=\"602\" height=\"437\" src=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2025\/10\/calendrier.png?fit=602%2C437&amp;ssl=1\" class=\"attachment-large size-large wp-image-42171\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2025\/10\/calendrier.png?w=602&amp;ssl=1 602w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2025\/10\/calendrier.png?resize=300%2C218&amp;ssl=1 300w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2025\/10\/calendrier.png?resize=150%2C109&amp;ssl=1 150w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2025\/10\/calendrier.png?resize=207%2C150&amp;ssl=1 207w, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2025\/10\/calendrier.png?resize=277%2C201&amp;ssl=1 277w\" sizes=\"(max-width: 602px) 100vw, 602px\" data-attachment-id=\"42171\" data-permalink=\"https:\/\/ccmprimaire.be\/wp\/accueil\/calendrier-3\/\" data-orig-file=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2025\/10\/calendrier.png?fit=602%2C437&amp;ssl=1\" data-orig-size=\"602,437\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"calendrier\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2025\/10\/calendrier.png?fit=602%2C437&amp;ssl=1\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f2d79c elementor-widget elementor-widget-text-editor\" data-id=\"5f2d79c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Agenda de l&rsquo;\u00e9cole primaire<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-94a2b31 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"94a2b31\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/ccmprimaire.be\/wp\/agenda-2023-2024\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Plus d'infos<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-ed2bd61\" data-id=\"ed2bd61\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-29a1ec0 elementor-widget elementor-widget-image\" data-id=\"29a1ec0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"29390\" data-permalink=\"https:\/\/ccmprimaire.be\/wp\/accueil\/portail-1\/\" data-orig-file=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2021\/04\/portail-1.jpg?fit=150%2C150&amp;ssl=1\" data-orig-size=\"150,150\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"portail (1)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2021\/04\/portail-1.jpg?fit=150%2C150&amp;ssl=1\" width=\"150\" height=\"150\" src=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2021\/04\/portail-1.jpg?fit=150%2C150&amp;ssl=1\" class=\"attachment-large size-large wp-image-29390\" alt=\"\" data-attachment-id=\"29390\" data-permalink=\"https:\/\/ccmprimaire.be\/wp\/accueil\/portail-1\/\" data-orig-file=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2021\/04\/portail-1.jpg?fit=150%2C150&amp;ssl=1\" data-orig-size=\"150,150\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"portail (1)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2021\/04\/portail-1.jpg?fit=150%2C150&amp;ssl=1\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ab220d elementor-widget elementor-widget-text-editor\" data-id=\"2ab220d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Tout savoir sur le portail CCM<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7276107 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"7276107\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/faq.apschool.be\/authentication\/login\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Plus d'infos<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-72a7952\" data-id=\"72a7952\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-faa2cb6 elementor-widget elementor-widget-image\" data-id=\"faa2cb6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"29393\" data-permalink=\"https:\/\/ccmprimaire.be\/wp\/accueil\/copie-de-copie-de-copie-de-menu\/\" data-orig-file=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2021\/04\/Copie-de-Copie-de-Copie-de-menu.jpg?fit=150%2C150&amp;ssl=1\" data-orig-size=\"150,150\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Copie de Copie de Copie de menu\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2021\/04\/Copie-de-Copie-de-Copie-de-menu.jpg?fit=150%2C150&amp;ssl=1\" width=\"150\" height=\"150\" src=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2021\/04\/Copie-de-Copie-de-Copie-de-menu.jpg?fit=150%2C150&amp;ssl=1\" class=\"attachment-large size-large wp-image-29393\" alt=\"\" data-attachment-id=\"29393\" data-permalink=\"https:\/\/ccmprimaire.be\/wp\/accueil\/copie-de-copie-de-copie-de-menu\/\" data-orig-file=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2021\/04\/Copie-de-Copie-de-Copie-de-menu.jpg?fit=150%2C150&amp;ssl=1\" data-orig-size=\"150,150\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Copie de Copie de Copie de menu\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2021\/04\/Copie-de-Copie-de-Copie-de-menu.jpg?fit=150%2C150&amp;ssl=1\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d85b5f0 elementor-widget elementor-widget-text-editor\" data-id=\"d85b5f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Recharger la carte magn\u00e9tique<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c4a4598 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"c4a4598\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/plateforme.apschool.be\/authentication\/login\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Plus d'infos<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Toute l&rsquo;actualit\u00e9\u00a0de l&rsquo;\u00e9cole\u00a0 Plus d&rsquo;infos Agenda de l&rsquo;\u00e9cole primaire Plus d&rsquo;infos Tout savoir sur le portail CCM Plus d&rsquo;infos Recharger la carte magn\u00e9tique Plus d&rsquo;infos <a class=\"continue-reading-link\" href=\"https:\/\/ccmprimaire.be\/wp\/cryout_serious_slide\/42987\/\">Lire la suite<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-29360","page","type-page","status-publish","hentry"],"jetpack_shortlink":"https:\/\/wp.me\/P6UVqj-7Dy","jetpack-related-posts":[{"id":7946,"url":"https:\/\/ccmprimaire.be\/wp\/infos-pratiques\/contact-webmaster\/","url_meta":{"origin":29360,"position":0},"title":"Contact Webmaster","author":"Mr Arnaud","date":"10 d\u00e9cembre 2016","format":false,"excerpt":"Envoyer un mail au Webmaster[contact-form-7 id=\"5428\" title=\"Contact\"]","rel":"","context":"Article similaire","block_context":{"text":"Article similaire","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":7954,"url":"https:\/\/ccmprimaire.be\/wp\/infos-pratiques\/contact-secretariat\/","url_meta":{"origin":29360,"position":1},"title":"Contact Secr\u00e9tariat","author":"Mr Arnaud","date":"10 d\u00e9cembre 2016","format":false,"excerpt":"Envoyer un mail au Secr\u00e9tariat de l'\u00e9cole primaire[contact-form-7 id=\"7952\" title=\"Contact secr\u00e9tariat\"] \u00a0 \u00a0","rel":"","context":"Article similaire","block_context":{"text":"Article similaire","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":7949,"url":"https:\/\/ccmprimaire.be\/wp\/infos-pratiques\/contact-direction\/","url_meta":{"origin":29360,"position":2},"title":"Contact Direction","author":"Mr Arnaud","date":"10 d\u00e9cembre 2016","format":false,"excerpt":"Envoyer un mail \u00e0 la Direction de l'\u00e9cole primaire[contact-form-7 id=\"7945\" title=\"Contact direction\"]","rel":"","context":"Article similaire","block_context":{"text":"Article similaire","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8436,"url":"https:\/\/ccmprimaire.be\/wp\/presentation-de-lecole\/roi-garderies\/","url_meta":{"origin":29360,"position":3},"title":"R\u00e8glement","author":"Mr Arnaud","date":"18 janvier 2017","format":false,"excerpt":"\u00a0L\u2019accueil Temps Libre organis\u00e9 par l\u2019\u00e9cole Primaire Libre Subventionn\u00e9e Mixte \u00e0 Braine-l\u2019Alleud R\u00e8glement d\u2019Ordre Int\u00e9rieur En conformit\u00e9 avec le d\u00e9cret \u00ab\u00a0Accueil Temps Libre\u00a0\u00bb, les objectifs poursuivis sont\u00a0: L\u2019\u00e9panouissement global des enfants par l\u2019organisation d\u2019activit\u00e9s de d\u00e9veloppement multidimensionnel adapt\u00e9es \u00e0 leurs capacit\u00e9s et \u00e0 leurs rythmes. L\u2019\u00e9cole occupe une place importante\u2026","rel":"","context":"Article similaire","block_context":{"text":"Article similaire","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":17738,"url":"https:\/\/ccmprimaire.be\/wp\/presentation-de-lecole\/accueil-temps-libre-roi\/","url_meta":{"origin":29360,"position":4},"title":"Accueil temps libre \u2013 ROI","author":"Mr Arnaud","date":"12 novembre 2018","format":false,"excerpt":"\u00a0 L\u2019accueil Temps Libre organis\u00e9 par l\u2019\u00e9cole Primaire Libre Subventionn\u00e9e Mixte \u00e0 Braine-l\u2019Alleud R\u00e8glement d\u2019Ordre Int\u00e9rieur \u00a0 En conformit\u00e9 avec le d\u00e9cret \u00ab\u00a0Accueil Temps Libre\u00a0\u00bb, les objectifs poursuivis sont\u00a0: \u00a0 L\u2019\u00e9panouissement global des enfants par l\u2019organisation d\u2019activit\u00e9s de d\u00e9veloppement multidimensionnel adapt\u00e9es \u00e0 leurs capacit\u00e9s et \u00e0 leurs rythmes. L\u2019\u00e9cole occupe\u2026","rel":"","context":"Article similaire","block_context":{"text":"Article similaire","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":37682,"url":"https:\/\/ccmprimaire.be\/wp\/elementor-37682\/","url_meta":{"origin":29360,"position":5},"title":"L&rsquo;\u00e9quipe maternelle","author":"Mr Arnaud","date":"12 juillet 2023","format":false,"excerpt":"Equipe p\u00e9dagogique 2025-2026 Accueil - M1 M2 - M3 Aide p\u00e9dagogique Acc-M1A\u00a0Mme C\u00e9cile DEFRENNEAcc-M1B\u00a0Mme Valentine MERTENSAcc-M1C\u00a0Mme Jennifer VOLKAERTS\u00a0 M2A-M3A\u00a0Mme Ma\u00eblle DELABRE M2B-M3B Mme Marie CATRY M2C-M3C\u00a0Mme B\u00e9n\u00e9dicte DUFAY Gym - Psychomotricit\u00e9\u00a0M. Thibaut ROSE","rel":"","context":"Article similaire","block_context":{"text":"Article similaire","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2023\/07\/Sans-titre-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2023\/07\/Sans-titre-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2023\/07\/Sans-titre-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/ccmprimaire.be\/wp\/wp-content\/uploads\/2023\/07\/Sans-titre-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/ccmprimaire.be\/wp\/wp-json\/wp\/v2\/pages\/29360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccmprimaire.be\/wp\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ccmprimaire.be\/wp\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ccmprimaire.be\/wp\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ccmprimaire.be\/wp\/wp-json\/wp\/v2\/comments?post=29360"}],"version-history":[{"count":71,"href":"https:\/\/ccmprimaire.be\/wp\/wp-json\/wp\/v2\/pages\/29360\/revisions"}],"predecessor-version":[{"id":42565,"href":"https:\/\/ccmprimaire.be\/wp\/wp-json\/wp\/v2\/pages\/29360\/revisions\/42565"}],"wp:attachment":[{"href":"https:\/\/ccmprimaire.be\/wp\/wp-json\/wp\/v2\/media?parent=29360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}